{"id":74420,"date":"2020-09-14T17:04:25","date_gmt":"2020-09-14T20:04:25","guid":{"rendered":"https:\/\/homologa.jfrs.jus.br\/memoria\/?page_id=74420"},"modified":"2022-09-30T20:35:43","modified_gmt":"2022-09-30T23:35:43","slug":"fios-da-historia-serie-primeiros-juizes","status":"publish","type":"post","link":"https:\/\/homologa.jfrs.jus.br\/memoria\/fios-da-historia-serie-primeiros-juizes\/","title":{"rendered":"Fios da Hist\u00f3ria &#8211; S\u00e9rie Primeiros Ju\u00edzes"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p>Estamos participando da 14\u00aa Primavera dos Museus, evento promovido pelo Instituto Brasileiro de Museus\/IBRAM com intuito de mobilizar institui\u00e7\u00f5es museol\u00f3gicas de todo pa\u00eds. Com o tema \u201cMundo Digital: museus em transforma\u00e7\u00e3o\u201d, a temporada de eventos acontece entre os dias 21 e 27 de setembro. O Memorial da JFRS vai apresentar, atrav\u00e9s de uma s\u00e9rie de postagens (fio), alguns dos primeiros ju\u00edzes empossados nas seccionais ga\u00fachas, na \u00e9poca da primeira fase da Justi\u00e7a Federal RS, de 1890 a 1937.&nbsp; Para saber mais, segue o fio!<\/p>\n\n\n\n<p>A Justi\u00e7a Federal foi criada pelo Decreto n\u00ba 848, de 11 de outubro de 1890, do Governo Provis\u00f3rio, que definiu que ela seria composta pelo Supremo Tribunal Federal (STF) e por ju\u00edzes federais ou seccionais. Cada unidade federativa corresponderia a uma se\u00e7\u00e3o judicial, tendo por sede a respectiva capital, com apenas um juiz titular (vital\u00edcio) e um substituto (com mandato de seis anos), todos nomeados pelo Presidente da Rep\u00fablica ap\u00f3s aprova\u00e7\u00e3o do Senado.<\/p>\n\n\n\n<p>A Constitui\u00e7\u00e3o dos Estados Unidos do Brasil, promulgada em 1891, garantiu a exist\u00eancia da Justi\u00e7a Federal e estabeleceu que o STF, com quinze ju\u00edzes, teria sede no Distrito Federal (na \u00e9poca, o Rio de Janeiro). Logo ap\u00f3s a instala\u00e7\u00e3o do STF, em 28 de fevereiro daquele ano, foram empossados os ju\u00edzes e os funcion\u00e1rios da Justi\u00e7a Federal.<\/p>\n\n\n\n<p>A Lei 221\/1894 criou tr\u00eas cargos de juiz suplente para as sedes das Se\u00e7\u00f5es (capitais), os quais seriam exercidos somente na aus\u00eancia ou impedimento do juiz substituto. Os suplentes eram nomeados pelo Presidente da Rep\u00fablica, sob indica\u00e7\u00e3o do juiz seccional, para servirem durante quatro anos.<\/p>\n\n\n\n<p>Em 1896, o governo federal criou oito circunscri\u00e7\u00f5es judici\u00e1rias no Rio Grande do Sul e tr\u00eas cargos de suplentes do juiz substituto para cada uma delas (Decreto 2220, de 23\/01\/1896).<\/p>\n\n\n\n<p>Fonte: Relat\u00f3rios do Minist\u00e9rio da Justi\u00e7a (RJ) \u2013 1891 a 1927. Exposi\u00e7\u00e3o apresentada ao Chefe do Governo Provis\u00f3rio da Rep\u00fablica dos Estados Unidos do Brasil pelo General Dr. Manoel Ferraz de Campos Salles, Ministro e Secret\u00e1rio de Estado dos Neg\u00f3cios da Justi\u00e7a, em janeiro de 1891. Rio de Janeiro: Imprensa Nacional, 1891. p. 50-53. (Dispon\u00edvel em: http:\/\/memoria.bn.br\/DocReader\/873837\/52)<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-medium\"><img decoding=\"async\" src=\"https:\/\/homologa.jfrs.jus.br\/memoria\/wp-content\/uploads\/2022\/09\/2-Herminio-3-400x400-1.png\" alt=\"Ilustra\u00e7\u00e3o com a foto de um homem de cabelos e barba curta brancos,  usando \u00f3culos, em preto e branco. Abaixo da foto o nome Herm\u00ednio Francisco do Esp\u00edrito Santo. ao lado da foto o texto Exposi\u00e7\u00e3o virtual Fio da Hist\u00f3ria s\u00e9rie primeiros ju\u00edzes. logo da 14\u00aa Primavera dos Museus. Memorial da Justi\u00e7a Federal do RS\" class=\"wp-image-74565\"\/><\/figure><\/div>\n\n\n\n<p>O pernambucano HERM\u00cdNIO FRANCISCO DO ESP\u00cdRITO SANTO foi o primeiro juiz federal da Se\u00e7\u00e3o do Rio Grande do Sul. Nomeado por decreto do Governo Provis\u00f3rio da Rep\u00fablica em 20 de novembro de 1890, Herm\u00ednio entrou em exerc\u00edcio no dia 2 de mar\u00e7o de 1891, data da inaugura\u00e7\u00e3o da Justi\u00e7a Federal em Porto Alegre. Na \u00e9poca, a Justi\u00e7a funcionava ainda sem sede pr\u00f3pria e o magistrado costumava despachar em sua resid\u00eancia. As audi\u00eancias ocorriam uma vez por semana no antigo pr\u00e9dio da C\u00e2mara Municipal, localizado na pra\u00e7a Marechal Deodoro (pra\u00e7a da Matriz). Antes, Herm\u00ednio Francisco do Esp\u00edrito Santo havia exercido os cargos de juiz municipal e de \u00f3rf\u00e3os nos munic\u00edpios de S\u00e3o Jos\u00e9 do Norte (RS) e Cruz Alta (RS), juiz de direito da comarca de Barreirinhos (MA), vice-presidente da prov\u00edncia de Santa Catarina, chefe de pol\u00edcia nas prov\u00edncias do Maranh\u00e3o, Paran\u00e1 e Rio Grande do Sul, e desembargador do Tribunal da Rela\u00e7\u00e3o de Porto Alegre. Casou-se com Adelaide, irm\u00e3 de J\u00falio Prates de Castilhos. Herm\u00ednio do Esp\u00edrito Santo atuou como juiz federal no Rio Grande do Sul at\u00e9 1894, quando foi promovido a Ministro do Supremo Tribunal Federal.<\/p>\n\n\n\n<p>Foto: acervo do STF<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-medium\"><img decoding=\"async\" src=\"https:\/\/homologa.jfrs.jus.br\/memoria\/wp-content\/uploads\/2022\/09\/3-Ribeiro-Dantas-400x400-1.png\" alt=\"Ilustra\u00e7\u00e3o com a foto de um homem de cabelos e bigode brancos,  , em preto e branco. Abaixo da foto o nome Francisco  de souza ribeiro dantas filho. ao lado da foto o texto Exposi\u00e7\u00e3o virtual Fio da Hist\u00f3ria s\u00e9rie primeiros ju\u00edzes. logo da 14\u00aa Primavera dos Museus. Memorial da Justi\u00e7a Federal do RS\" class=\"wp-image-74563\"\/><\/figure><\/div>\n\n\n\n<p>Francisco de Souza Ribeiro Dantas Filho foi nomeado pelo Governo Provis\u00f3rio da Rep\u00fablica em 24 de novembro de 1890, sendo o primeiro juiz federal substituto da Se\u00e7\u00e3o do Rio Grande do Sul. Trabalhou na Junta Municipal de Santo \u00c2ngelo entre os anos de 1890 e 1891 e, em fevereiro de 1893, retornou \u00e0quela cidade como Juiz Distrital.<\/p>\n\n\n\n<p>Foto: Rio Grande do Sul em Revista, 1928\/Acervo do Arquivo Hist\u00f3rico de Porto Alegre Moys\u00e9s Vellinho<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-medium\"><img decoding=\"async\" src=\"https:\/\/homologa.jfrs.jus.br\/memoria\/wp-content\/uploads\/2022\/09\/4-Poggi-com-texto-400x400-1.png\" alt=\"Ilustra\u00e7\u00e3o com o curr\u00edculo de Jo\u00e3o Francisco Poggi de Figueiredo. ao lado da foto o texto Exposi\u00e7\u00e3o virtual Fio da Hist\u00f3ria s\u00e9rie primeiros ju\u00edzes. logo da 14\u00aa Primavera dos Museus. Memorial da Justi\u00e7a Federal do RS\" class=\"wp-image-74566\"\/><\/figure><\/div>\n\n\n\n<p>JO\u00c3O FRANCISCO POGGI DE FIGUEIREDO e os magistrados que o antecederam atuaram num per\u00edodo conturbado, marcado pela Revolu\u00e7\u00e3o Federalista\/RS (1893-1895) que, articulada com a Revolta da Armada\/RJ (1893-1895), chegou a amea\u00e7ar a estabilidade da jovem Rep\u00fablica. Proferiu decis\u00f5es em processos de relev\u00e2ncia hist\u00f3rica, entre os quais in\u00fameras ordens de <em>habeas corpus<\/em> \u2013 impetradas em favor de maragatos, que se sentiam v\u00edtimas de persegui\u00e7\u00e3o pol\u00edtica \u2013 e pedidos de indeniza\u00e7\u00e3o apresentados por produtores rurais que foram obrigados a abastecer as tropas durante a guerra civil.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-medium\"><img decoding=\"async\" src=\"https:\/\/homologa.jfrs.jus.br\/memoria\/wp-content\/uploads\/2022\/09\/5-Sampaio-400x400-1.png\" alt=\"Ilustra\u00e7\u00e3o com a foto em preto e branco de um homem de cabelos e bigode brancos, usando \u00f3culos escuro. Abaixo da foto o nome Jos\u00e9 Luiz de Sampaio. ao lado da foto o texto Exposi\u00e7\u00e3o virtual Fio da Hist\u00f3ria s\u00e9rie primeiros ju\u00edzes. logo da 14\u00aa Primavera dos Museus. Memorial da Justi\u00e7a Federal do RS\" class=\"wp-image-74567\"\/><\/figure><\/div>\n\n\n\n<p>Luiz Jos\u00e9 de Sampaio inicia sua carreira na magistratura federal em 1901, como juiz substituto da Se\u00e7\u00e3o do Rio Grande do Sul. Em 1907, quando termina o prazo legal de seis anos, \u00e9 reconduzido. Classificou-se em primeiro lugar no concurso para o cargo de juiz federal promovido em 1914, em virtude da aposentadoria de Jo\u00e3o Francisco Poggi de Figueiredo. Ficou afastado da jurisdi\u00e7\u00e3o por um longo per\u00edodo, em tratamento m\u00e9dico na Europa. Toma posse no cargo em junho de 1923, no calor da guerra entre maragatos e chimangos. Durante seu afastamento, o juiz substituto Luiz Affonso Chagas exerceu a titularidade nos processos da Se\u00e7\u00e3o.<\/p>\n\n\n\n<p>Foto: A Federa\u00e7\u00e3o, 25out1933\/Hemeroteca do Museu da Comunica\u00e7\u00e3o Hip\u00f3lito Jos\u00e9 da Costa<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-medium\"><img decoding=\"async\" src=\"https:\/\/homologa.jfrs.jus.br\/memoria\/wp-content\/uploads\/2022\/09\/6-Vergara-400x400-1.png\" alt=\"Ilustra\u00e7\u00e3o com a foto em preto e branco de um homem de cabelos preto e usando \u00f3culos redondo. Abaixo da foto o nome Oswaldo Fernandes Vergara. ao lado da foto o texto Exposi\u00e7\u00e3o virtual Fio da Hist\u00f3ria s\u00e9rie primeiros ju\u00edzes. logo da 14\u00aa Primavera dos Museus. Memorial da Justi\u00e7a Federal do RS\" class=\"wp-image-74568\"\/><\/figure><\/div>\n\n\n\n<p>OSWALDO FERNANDES VERGARA exerceu, em dois per\u00edodos de quatro anos, a fun\u00e7\u00e3o de suplente dos ju\u00edzes substitutos Luiz Affonso Chagas e Francisco Fabres da Rocha.<\/p>\n\n\n\n<p>Vergara nasceu na cidade de Jaguar\u00e3o (RS) em 1883. Na capital, trabalhou como guarda-livros at\u00e9 1900, quando assume o cargo de escritur\u00e1rio do Tesouro do Estado. Foi professor de portugu\u00eas e franc\u00eas na Escola Complementar (hoje Instituto de Educa\u00e7\u00e3o Flores da Cunha) e na Escola do Com\u00e9rcio (atual Faculdade de Ci\u00eancias Econ\u00f4micas e Cont\u00e1beis da UFRGS). Bacharelou-se na Faculdade Livre de Direito de Porto Alegre em 1907 e, em seguida, instalou seu escrit\u00f3rio de advocacia na antiga rua Nova (Andrade Neves). Foi delegado de pol\u00edcia do 2\u00ba distrito da capital. Em 1926, participou da funda\u00e7\u00e3o do Instituto dos Advogados do Rio Grande do Sul. No ano seguinte, foi eleito presidente do Conselho Municipal de Porto Alegre, mantendo-se no cargo at\u00e9 1930.<\/p>\n\n\n\n<p>Vergara foi o primeiro a receber, em 1967, a comenda de Advogado Em\u00e9rito pela se\u00e7\u00e3o estadual da OAB, e, desde sua morte, em 1973, seu nome intitula a Comanda Oswaldo Vergara, importante distin\u00e7\u00e3o a ser conferida aos not\u00e1veis da \u00e1rea jur\u00eddica. Casou-se com Isabel Dias de Castro, com quem teve sete filhos, entre eles o escritor Telmo Vergara.<\/p>\n\n\n\n<p>Foto: Revista M\u00e1scara, 1918\/Hemeroteca do Museu da Comunica\u00e7\u00e3o Hip\u00f3lito Jos\u00e9 da Costa<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-medium\"><img decoding=\"async\" src=\"https:\/\/homologa.jfrs.jus.br\/memoria\/wp-content\/uploads\/2022\/09\/7-Luiz-Chagas-400x400-1.png\" alt=\"Ilustra\u00e7\u00e3o com a foto em preto e branco de um homem de bigode preto. Abaixo da foto o nome Luiz Affonso Chagas. ao lado da foto o texto Exposi\u00e7\u00e3o virtual Fio da Hist\u00f3ria s\u00e9rie primeiros ju\u00edzes. logo da 14\u00aa Primavera dos Museus. Memorial da Justi\u00e7a Federal do RS\" class=\"wp-image-74569\"\/><\/figure><\/div>\n\n\n\n<p>Luiz Affonso Chagas exerceu o cargo de Procurador da Rep\u00fablica no RS de 1914 at\u00e9 1917, quando foi nomeado juiz substituto da Se\u00e7\u00e3o do Rio Grande do Sul. Removeu-se para a Se\u00e7\u00e3o de Alagoas em 1924 e, mais tarde, para o Paran\u00e1, onde atuou como juiz seccional at\u00e9 ser extinta a Justi\u00e7a Federal, em 1937.<\/p>\n\n\n\n<p>Foto: \u00c1lbum dos Bandoleiros<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-medium\"><img decoding=\"async\" src=\"https:\/\/homologa.jfrs.jus.br\/memoria\/wp-content\/uploads\/2022\/09\/8-Fabres-400x400-1.png\" alt=\"Ilustra\u00e7\u00e3o com a foto em preto e branco de um homem de cabelos  preto, usando \u00f3culos arredondado. Abaixo da foto o nome Francisco Fabres da Rocha. ao lado da foto o texto Exposi\u00e7\u00e3o virtual Fio da Hist\u00f3ria s\u00e9rie primeiros ju\u00edzes. logo da 14\u00aa Primavera dos Museus. Memorial da Justi\u00e7a Federal do RS\" class=\"wp-image-74570\"\/><\/figure><\/div>\n\n\n\n<p>FRANCISCO FABRES DA ROCHA diplomou-se em Direito na Faculdade Livre do Rio de Janeiro em 1917. Instalou seu escrit\u00f3rio de advocacia na rua Dem\u00e9trio Ribeiro, em Porto Alegre. Escreveu artigos para diversos jornais do Rio Grande do Sul, entre eles a Opini\u00e3o P\u00fablica, Situa\u00e7\u00e3o, O Dia e A Rea\u00e7\u00e3o. Atuou como juiz distrital nos munic\u00edpios ga\u00fachos de S\u00e3o Jos\u00e9 do Norte, S\u00e3o Luiz Gonzaga e Jaguar\u00e3o. Foi Secret\u00e1rio do Munic\u00edpio de Porto Alegre nas gest\u00f5es dos intendentes Ot\u00e1vio Rocha e Alberto Bins. Exerceu o cargo de juiz federal substituto da Se\u00e7\u00e3o do Rio Grande do Sul no per\u00edodo de 1928 a 1937.<\/p>\n\n\n\n<p>Foto: Vida Carioca, 1925\/ Hemeroteca da Biblioteca Nacional Digital<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-medium\"><img decoding=\"async\" src=\"https:\/\/homologa.jfrs.jus.br\/memoria\/wp-content\/uploads\/2022\/09\/9-Ney-Wiedmann-400x400-1.png\" alt=\"Ilustra\u00e7\u00e3o com a foto em preto e branco de um homem de cabelos  preto, usando fraque. Abaixo da foto o nome Ney da Silva Widmann. ao lado da foto o texto Exposi\u00e7\u00e3o virtual Fio da Hist\u00f3ria s\u00e9rie primeiros ju\u00edzes. logo da 14\u00aa Primavera dos Museus. Memorial da Justi\u00e7a Federal do RS\" class=\"wp-image-74571\"\/><\/figure><\/div>\n\n\n\n<p>NEY DA SILVA WIEDMANN formou-se na Faculdade de Direito de Porto Alegre em 1916. Foi Secret\u00e1rio da Procuradoria Geral do Estado, juiz de direito nas comarcas de Lagoa Vermelha, Bento Gon\u00e7alves e Santana do Livramento. Nomeado juiz federal em 1933, exerceu o cargo at\u00e9 a implanta\u00e7\u00e3o do Estado Novo, em 1937, quando a Justi\u00e7a Federal foi extinta. Mais tarde, retornou \u00e0 magistratura estadual, sendo promovido por merecimento em 1949 e aposentando-se em 1957 no cargo de Desembargador do Tribunal de Justi\u00e7a do RS.<\/p>\n\n\n\n<p>Foto: acervo da Ajuris<\/p>\n\n\n\n<p>Assista a&nbsp;<em>live<\/em>&nbsp;Primeiros Ju\u00edzes, promovida no dia 24\/9,&nbsp;com Tassiara Jaqueline Fanck Kich, Arquivista e Diretora do N\u00facleo de Documenta\u00e7\u00e3o e Mem\u00f3ria da JFRS, Adriana Bednarz, Historiadora e Servidora do N\u00facleo de Documenta\u00e7\u00e3o e Mem\u00f3ria, <a href=\"https:\/\/www.youtube.com\/watch?v=wItQM3vwutQ\">no canal do Youtube da JFRS<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estamos participando da 14\u00aa Primavera dos Museus, evento promovido pelo Instituto Brasileiro de Museus\/IBRAM com intuito de mobilizar institui\u00e7\u00f5es museol\u00f3gicas de todo pa\u00eds. Com o tema \u201cMundo Digital: museus em transforma\u00e7\u00e3o\u201d, a temporada de eventos acontece entre os dias 21 [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21,36],"tags":[],"class_list":["post-74420","post","type-post","status-publish","format-standard","hentry","category-exposicoes-e-eventos","category-exposicoes-virtuais"],"_links":{"self":[{"href":"https:\/\/homologa.jfrs.jus.br\/memoria\/wp-json\/wp\/v2\/posts\/74420","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/homologa.jfrs.jus.br\/memoria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/homologa.jfrs.jus.br\/memoria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/homologa.jfrs.jus.br\/memoria\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/homologa.jfrs.jus.br\/memoria\/wp-json\/wp\/v2\/comments?post=74420"}],"version-history":[{"count":3,"href":"https:\/\/homologa.jfrs.jus.br\/memoria\/wp-json\/wp\/v2\/posts\/74420\/revisions"}],"predecessor-version":[{"id":80714,"href":"https:\/\/homologa.jfrs.jus.br\/memoria\/wp-json\/wp\/v2\/posts\/74420\/revisions\/80714"}],"wp:attachment":[{"href":"https:\/\/homologa.jfrs.jus.br\/memoria\/wp-json\/wp\/v2\/media?parent=74420"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/homologa.jfrs.jus.br\/memoria\/wp-json\/wp\/v2\/categories?post=74420"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/homologa.jfrs.jus.br\/memoria\/wp-json\/wp\/v2\/tags?post=74420"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}