{"id":35823,"date":"2022-09-27T16:18:34","date_gmt":"2022-09-27T19:18:34","guid":{"rendered":"https:\/\/homologa.jfrs.jus.br\/memoria\/?p=35823"},"modified":"2022-10-11T14:49:50","modified_gmt":"2022-10-11T17:49:50","slug":"exposicao-contando-historiasbuscando-justica-o-periodo-de-1890-1930","status":"publish","type":"post","link":"https:\/\/homologa.jfrs.jus.br\/memoria\/exposicao-contando-historiasbuscando-justica-o-periodo-de-1890-1930\/","title":{"rendered":"Exposi\u00e7\u00e3o &#8220;Contando Hist\u00f3rias\u2026Buscando Justi\u00e7a: o per\u00edodo de 1890-1930&#8221;"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"506\" src=\"https:\/\/homologa.jfrs.jus.br\/memoria\/wp-content\/uploads\/2022\/09\/Imagem-Oficial_-at-14.03.24-1024x506.jpeg\" alt=\"Espa\u00e7o do memorial que ilustra a exposi\u00e7\u00e3o . H\u00e1 processos sobre mesas , abertos em apoiadores. Ao lado esquerdo da foto, uma coluna com adesivos e textos. No outro lado do espa\u00e7o, \u00e0 direita dessa coluna , mais ao fundo , h\u00e1 uma janela mostrando o rio Gua\u00edba. Ap\u00f3s, na parede do lado direito h\u00e1 um adesivo grande, com texto e foto.\" class=\"wp-image-35824\" srcset=\"https:\/\/homologa.jfrs.jus.br\/memoria\/wp-content\/uploads\/2022\/09\/Imagem-Oficial_-at-14.03.24-1024x506.jpeg 1024w, https:\/\/homologa.jfrs.jus.br\/memoria\/wp-content\/uploads\/2022\/09\/Imagem-Oficial_-at-14.03.24-300x148.jpeg 300w, https:\/\/homologa.jfrs.jus.br\/memoria\/wp-content\/uploads\/2022\/09\/Imagem-Oficial_-at-14.03.24-768x380.jpeg 768w, https:\/\/homologa.jfrs.jus.br\/memoria\/wp-content\/uploads\/2022\/09\/Imagem-Oficial_-at-14.03.24.jpeg 1040w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>Exposi\u00e7\u00e3o 2019<\/figcaption><\/figure><\/div>\n\n\n\n<p>A mostra apresentou parte do contexto hist\u00f3rico do Rio Grande do Sul sob a \u00f3tica de processos correlacionados com fatos memor\u00e1veis que ocorreram no sul do Brasil, dentro de um cen\u00e1rio marcado por uma s\u00e9rie de eventos pol\u00edticos, econ\u00f4micos e sociais ao longo da segunda metade do s\u00e9culo XIX. No ano de 1889, nosso pa\u00eds testemunhava a derrubada da monarquia e o surgimento da Rep\u00fablica dos Estados Unidos do Brasil. Com o estabelecimento do modelo republicano como forma de governo, a Constitui\u00e7\u00e3o de 1891, influenciada pelas vertentes anglo-sax\u00f4nicas do Direito, deu forma \u00e0 triparti\u00e7\u00e3o dos poderes, firmando a composi\u00e7\u00e3o e as compet\u00eancias do judici\u00e1rio brasileiro. \u00c0 \u00e9poca, conforme determinado pelo Decreto n\u00b0 848 de 11 de outubro de 1890, do Governo Provis\u00f3rio, o judici\u00e1rio se dividia entre a Justi\u00e7a Federal e Justi\u00e7a Estadual. <\/p>\n\n\n\n<p>As pe\u00e7as, as fotos e os processos expostos ilustraram o cen\u00e1rio da \u00e9poca, atrav\u00e9s de um recorte historiogr\u00e1fico da chamada Primeira Rep\u00fablica, compreendida no per\u00edodo de 1889 at\u00e9 1930: <br> demonstram um per\u00edodo caracterizado pelas disputas pol\u00edticas regionais e pelas rivalidades conciliat\u00f3rias entre as elites de S\u00e3o Paulo e Minas Gerais no \u00e2mbito nacional, encerradas com a ascens\u00e3o de Get\u00falio Vargas.<br> Os autos judiciais que estiveram expostos pertencem \u00e0 primeira fase da Justi\u00e7a Federal (1890-1937) e os objetos museol\u00f3gicos foram disponibilizados pelo Museu J\u00falio de Castilhos.<\/p>\n\n\n\n<p>Dentre os processos expostos, apareceram lit\u00edgios origin\u00e1rios da \u00e9poca do Imp\u00e9rio:<br> um dos processos apresentou a reivindica\u00e7\u00e3o de um terreno situado \u00e0s margens do Gua\u00edba, em Porto Alegre. A fam\u00edlia autora alegava ser herdeira dos direitos do dono do terreno, que partira para S\u00e3o Paulo em fun\u00e7\u00e3o da Revolu\u00e7\u00e3o Farroupilha e teve as terras apropriadas pelo governo.<\/p>\n\n\n\n<p>Em outra a\u00e7\u00e3o, p\u00f4de-se perceber que o fim da Revolu\u00e7\u00e3o Federalista significou a hegemonia do Partido Republicano no RS, mas n\u00e3o o fim das desaven\u00e7as entre grupos rivais com ressentimentos hist\u00f3ricos. Em 1889, um maragato impetra <em>habeas corpus<\/em> em seu favor ap\u00f3s ser v\u00edtima de atentado, dois anos antes. Segundo ele, os \u201cexaltados e intolerantes advers\u00e1rios maquinaram contra sua vida\u201d por ter sido revolucion\u00e1rio.<\/p>\n\n\n\n<p>Atrav\u00e9s da mostra foi poss\u00edvel ver como o estabelecimento do novo Direito, iniciado com a Constitui\u00e7\u00e3o Republicana em 1891, lidou com quest\u00f5es e lit\u00edgios ainda provenientes da \u00e9poca do Imp\u00e9rio. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/homologa.jfrs.jus.br\/memoria\/wp-content\/uploads\/2022\/09\/2019-FOTO2-Contando-Historias...-1024x683.jpg\" alt=\"Foto do espa\u00e7o do memoria com a os itens expostos\" class=\"wp-image-35838\" srcset=\"https:\/\/homologa.jfrs.jus.br\/memoria\/wp-content\/uploads\/2022\/09\/2019-FOTO2-Contando-Historias...-1024x683.jpg 1024w, https:\/\/homologa.jfrs.jus.br\/memoria\/wp-content\/uploads\/2022\/09\/2019-FOTO2-Contando-Historias...-300x200.jpg 300w, https:\/\/homologa.jfrs.jus.br\/memoria\/wp-content\/uploads\/2022\/09\/2019-FOTO2-Contando-Historias...-768x512.jpg 768w, https:\/\/homologa.jfrs.jus.br\/memoria\/wp-content\/uploads\/2022\/09\/2019-FOTO2-Contando-Historias...-1536x1024.jpg 1536w, https:\/\/homologa.jfrs.jus.br\/memoria\/wp-content\/uploads\/2022\/09\/2019-FOTO2-Contando-Historias...-2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>A exposi\u00e7\u00e3o contando<strong> hist\u00f3ria&#8230; Buscando justi\u00e7a: O Per\u00edodo de 1890-1930\u00a0<\/strong>permaneceu no Memorial at\u00e9 2022 devido ao fechamento dos museus pela pandemia da Covid-19.&#8221;).<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A mostra apresentou parte do contexto hist\u00f3rico do Rio Grande do Sul sob a \u00f3tica de processos correlacionados com fatos memor\u00e1veis que ocorreram no sul do Brasil, dentro de um cen\u00e1rio marcado por uma s\u00e9rie de eventos pol\u00edticos, econ\u00f4micos e [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[31,21],"tags":[],"class_list":["post-35823","post","type-post","status-publish","format-standard","hentry","category-2019-exposicoes-e-eventos","category-exposicoes-e-eventos"],"_links":{"self":[{"href":"https:\/\/homologa.jfrs.jus.br\/memoria\/wp-json\/wp\/v2\/posts\/35823","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/homologa.jfrs.jus.br\/memoria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/homologa.jfrs.jus.br\/memoria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/homologa.jfrs.jus.br\/memoria\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/homologa.jfrs.jus.br\/memoria\/wp-json\/wp\/v2\/comments?post=35823"}],"version-history":[{"count":6,"href":"https:\/\/homologa.jfrs.jus.br\/memoria\/wp-json\/wp\/v2\/posts\/35823\/revisions"}],"predecessor-version":[{"id":80789,"href":"https:\/\/homologa.jfrs.jus.br\/memoria\/wp-json\/wp\/v2\/posts\/35823\/revisions\/80789"}],"wp:attachment":[{"href":"https:\/\/homologa.jfrs.jus.br\/memoria\/wp-json\/wp\/v2\/media?parent=35823"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/homologa.jfrs.jus.br\/memoria\/wp-json\/wp\/v2\/categories?post=35823"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/homologa.jfrs.jus.br\/memoria\/wp-json\/wp\/v2\/tags?post=35823"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}