{"id":35710,"date":"2022-09-26T16:27:19","date_gmt":"2022-09-26T19:27:19","guid":{"rendered":"https:\/\/homologa.jfrs.jus.br\/memoria\/?p=35710"},"modified":"2022-09-30T18:05:19","modified_gmt":"2022-09-30T21:05:19","slug":"exposicao-diga-nao-ao-tabagismo","status":"publish","type":"post","link":"https:\/\/homologa.jfrs.jus.br\/memoria\/exposicao-diga-nao-ao-tabagismo\/","title":{"rendered":"Exposi\u00e7\u00e3o Diga n\u00e3o ao Tabagismo"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"330\" src=\"https:\/\/homologa.jfrs.jus.br\/memoria\/wp-content\/uploads\/2022\/09\/nao-tabagismo_montagem-editada-1024x330.png\" alt=\"Montagem com duas fotos: \u00e0 esquerda adesivos colados em vidro que fica na entrada do Memorial , com a programa\u00e7\u00e3o dos eventos referentes \u00e0 exposi\u00e7\u00e3o. Em um dos adesivos consta: &quot;29 de Agosto Dia Nacional de Combate ao Fumo (Lei Federal n. 7488 de 11.06.1986)&quot; e em letras garrafais ao centro consta &quot; Diga N\u00e3o ao Tabagismo&quot;.\" class=\"wp-image-35711\" srcset=\"https:\/\/homologa.jfrs.jus.br\/memoria\/wp-content\/uploads\/2022\/09\/nao-tabagismo_montagem-editada-1024x330.png 1024w, https:\/\/homologa.jfrs.jus.br\/memoria\/wp-content\/uploads\/2022\/09\/nao-tabagismo_montagem-editada-300x97.png 300w, https:\/\/homologa.jfrs.jus.br\/memoria\/wp-content\/uploads\/2022\/09\/nao-tabagismo_montagem-editada-768x247.png 768w, https:\/\/homologa.jfrs.jus.br\/memoria\/wp-content\/uploads\/2022\/09\/nao-tabagismo_montagem-editada-1536x495.png 1536w, https:\/\/homologa.jfrs.jus.br\/memoria\/wp-content\/uploads\/2022\/09\/nao-tabagismo_montagem-editada-2048x660.png 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<p>Sendo a sa\u00fade p\u00fablica uma das compet\u00eancias da Justi\u00e7a Federal, existem hoje, na esteira do judici\u00e1rio, discuss\u00f5es acerca da responsabilidade civil das ind\u00fastrias do setor fumageiro, dos comerciantes e do Estado.<\/p>\n\n\n\n<p>A Lei Federal n\u00ba 7488, de 1986 estabeleceu o dia 29 de agosto como \u201cDia Nacional de Combate ao Fumo\u201d, criando, assim, o compromisso de elaborar campanhas de combate ao tabagismo.<\/p>\n\n\n\n<p>Para marcar esta data, o Memorial da JFRS, em parceria com a Se\u00e7\u00e3o de Sa\u00fade, organizou um evento, com palestras, exposi\u00e7\u00e3o e campanha anti-tabagismo, com o intuito de sensibilizar magistrados, servidores e o p\u00fablico em geral sobre os malef\u00edcios do cigarro.<\/p>\n\n\n\n<p>Al\u00e9m da conscientiza\u00e7\u00e3o promovida, foi abordada a evolu\u00e7\u00e3o das leis que co\u00edbem o uso do tabaco em locais fechados, dando visibilidade e divulga\u00e7\u00e3o \u00e0s a\u00e7\u00f5es referentes ao assunto que tramitaram na Justi\u00e7a Federal.<\/p>\n\n\n\n<p>O evento contou com as parcerias do TJRS, da Se\u00e7\u00e3o Judici\u00e1ria de Santa Catarina, do Museu de Hist\u00f3ria da Medicina do RS e do Museu de Anatomia da Universidade Federal de Ci\u00eancias da Sa\u00fade de Porto Alegre.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"375\" height=\"500\" src=\"https:\/\/homologa.jfrs.jus.br\/memoria\/wp-content\/uploads\/2022\/09\/Nao-ao-tabagismo_pulmao-exposto_.jpg\" alt=\"Mulher colocando dentro de um expositor (de vidro com cerca de 140 cm de altura) um pulm\u00e3o danificado de um falecido - que era fumante.\" class=\"wp-image-35712\" srcset=\"https:\/\/homologa.jfrs.jus.br\/memoria\/wp-content\/uploads\/2022\/09\/Nao-ao-tabagismo_pulmao-exposto_.jpg 375w, https:\/\/homologa.jfrs.jus.br\/memoria\/wp-content\/uploads\/2022\/09\/Nao-ao-tabagismo_pulmao-exposto_-225x300.jpg 225w\" sizes=\"(max-width: 375px) 100vw, 375px\" \/><figcaption> Memorial da JFRS &#8211; Agosto\/Setembro 2014 <\/figcaption><\/figure><\/div>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sendo a sa\u00fade p\u00fablica uma das compet\u00eancias da Justi\u00e7a Federal, existem hoje, na esteira do judici\u00e1rio, discuss\u00f5es acerca da responsabilidade civil das ind\u00fastrias do setor fumageiro, dos comerciantes e do Estado. A Lei Federal n\u00ba 7488, de 1986 estabeleceu o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25,21],"tags":[],"class_list":["post-35710","post","type-post","status-publish","format-standard","hentry","category-25","category-exposicoes-e-eventos"],"_links":{"self":[{"href":"https:\/\/homologa.jfrs.jus.br\/memoria\/wp-json\/wp\/v2\/posts\/35710","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/homologa.jfrs.jus.br\/memoria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/homologa.jfrs.jus.br\/memoria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/homologa.jfrs.jus.br\/memoria\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/homologa.jfrs.jus.br\/memoria\/wp-json\/wp\/v2\/comments?post=35710"}],"version-history":[{"count":2,"href":"https:\/\/homologa.jfrs.jus.br\/memoria\/wp-json\/wp\/v2\/posts\/35710\/revisions"}],"predecessor-version":[{"id":35714,"href":"https:\/\/homologa.jfrs.jus.br\/memoria\/wp-json\/wp\/v2\/posts\/35710\/revisions\/35714"}],"wp:attachment":[{"href":"https:\/\/homologa.jfrs.jus.br\/memoria\/wp-json\/wp\/v2\/media?parent=35710"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/homologa.jfrs.jus.br\/memoria\/wp-json\/wp\/v2\/categories?post=35710"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/homologa.jfrs.jus.br\/memoria\/wp-json\/wp\/v2\/tags?post=35710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}