{"id":33863,"date":"2016-06-01T16:25:17","date_gmt":"2016-06-01T19:25:17","guid":{"rendered":"https:\/\/homologa.jfrs.jus.br\/memoria\/?page_id=33863"},"modified":"2022-09-27T15:52:34","modified_gmt":"2022-09-27T18:52:34","slug":"exposicoes-direitos-humanos-e-direitos-das-mulheres-a-justica-federal-e-as-representacoes-sociais-do-genero-feminino","status":"publish","type":"post","link":"https:\/\/homologa.jfrs.jus.br\/memoria\/exposicoes-direitos-humanos-e-direitos-das-mulheres-a-justica-federal-e-as-representacoes-sociais-do-genero-feminino\/","title":{"rendered":"Evento Direitos Humanos e Direitos das Mulheres: A Justi\u00e7a Federal e as Representa\u00e7\u00f5es Sociais do G\u00eanero Feminino"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-medium is-resized\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/homologa.jfrs.jus.br\/memoria\/wp-content\/uploads\/2022\/09\/Direitos-Humanos-E-Direitos-das-Mulheres-2-fotos-500x121-1.png\" alt=\"Duas fotos: a da esquerda com banners sobre o g\u00eanero feminino; \u00e0 direita, foto do espa\u00e7o memorial ; h\u00e1 uma mesa grande situada \u00e0 frente de uma coluna de espelhos, com processos \/ livros expostos.\" class=\"wp-image-62975\" width=\"630\" height=\"152\"\/><\/figure>\n\n\n\n<p>Durante os anos 2016 e 2017 foi realizado o evento \u201cDireitos\nHumanos, uma quest\u00e3o de justi\u00e7a\u201d, com objetivo de proporcionar espa\u00e7o para\nreflex\u00e3o sobre o tema e suas conex\u00f5es com o cotidiano da sociedade, por meio de\nexposi\u00e7\u00f5es, palestras e a\u00e7\u00f5es educativas, realizadas pela Justi\u00e7a Federal do RS\ne institui\u00e7\u00f5es parceiras, distribu\u00eddas sob cinco grandes eixos: <\/p>\n\n\n\n<p>a) Direitos Humanos e Direitos das Mulheres: A Justi\u00e7a Federal e\nas representa\u00e7\u00f5es sociais do g\u00eanero feminino \u2013 2016\/1;<\/p>\n\n\n\n<p>b) Direitos Humanos, Orienta\u00e7\u00e3o Sexual e Identidade de G\u00eanero: a\nhomossexualidade e as demandas envolvendo transexualidade na Justi\u00e7a Federal \u2013\n2016\/2;<\/p>\n\n\n\n<p>c) Direitos Humanos, Direito \u00e0 Inclus\u00e3o e Identidades \u00c9tnico-Raciais:\no debate na Justi\u00e7a Federal sobre aceita\u00e7\u00e3o das diversidades e a percep\u00e7\u00e3o do\noutro em seu amplo aspecto, e sobre cotas raciais e sociais, abordando a quest\u00e3o\ndo racismo e discrimina\u00e7\u00e3o \u2013 2016\/3;<\/p>\n\n\n\n<p>d) Direitos Humanos e Origem Nacional: identidades, migra\u00e7\u00e3o e\nnaturaliza\u00e7\u00e3o na Justi\u00e7a Federal \u2013 2017\/1;<\/p>\n\n\n\n<p>e) Direitos Humanos e Direito \u00e0 Sa\u00fade: A trajet\u00f3ria da Justi\u00e7a\nFederal em demandas por assist\u00eancia farmacol\u00f3gica e procedimentos no SUS \u2013\n2017\/2.<\/p>\n\n\n\n<p>No primeiro eixo foram abordadas quest\u00f5es significativas acerca do\npapel feminino em nossa sociedade e a posi\u00e7\u00e3o que a mulher ocupa perante\norganiza\u00e7\u00f5es, comunidades e fam\u00edlia, considerando a diversidade cultural e sua\ninflu\u00eancia ao redor do mundo.<\/p>\n\n\n\n<div class=\"wp-block-media-text alignwide has-media-on-the-right has-background has-background\" style=\"background-color:#fdf2fc;grid-template-columns:auto 56%\"><figure class=\"wp-block-media-text__media\"><img decoding=\"async\" src=\"https:\/\/homologa.jfrs.jus.br\/memoria\/wp-content\/uploads\/2022\/09\/Direitos-Humanos-E-Direitos-das-Mulheres-1-fotos-500x362-1.png\" alt=\"Montagem com 4 imagens: uma das fotos (acima \u00e0 esquerda) mostra uma parede com um grande mosaico constru\u00eddo com rostos \/ fotos de mulheres; a outra (acima \u00e0 direita) , h\u00e1 v\u00e1rios processos expostos; na foto abaixo \u00e0 esquerda, temos uma mapa de porto alegre que ilustra a localiza\u00e7\u00e3o de uma Col\u00f4nia Africana entre regi\u00e3o do bairro Bom Fim e Mon't Serrat. A foto abaixo \u00e0 direita , mostra um processo.\" class=\"wp-image-62976 size-medium\"\/><\/figure><div class=\"wp-block-media-text__content\">\n<p>Foram apresentados dados estat\u00edsticos alarmantes:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>48% das mulheres agredidas declaram que a viol\u00eancia aconteceu em sua pr\u00f3pria resid\u00eancia;<\/li><li>3 em cada 5 mulheres jovens j\u00e1 sofreram viol\u00eancia em relacionamentos;<\/li><li>56% dos homens admitem que j\u00e1 cometeram alguma forma de agress\u00e3o.<\/li><\/ul>\n<\/div><\/div>\n\n\n\n<p><\/p>\n\n\n\n<p>O evento tamb\u00e9m ilustrou o progresso em nossa legisla\u00e7\u00e3o, a partir\nda Lei Maria da Penha e da altera\u00e7\u00e3o no C\u00f3digo Penal com a introdu\u00e7\u00e3o do par\u00e1grafo\n9\u00ba, do art. 129, possibilitando que agressores de mulheres de \u00e2mbito dom\u00e9stico\nou familiar sejam presos em flagrante ou tenham sua pris\u00e3o preventiva\ndecretada.<\/p>\n\n\n\n<p>A abertura do evento foi contemplada com a palestra \u201cA Hist\u00f3ria da\nviol\u00eancia contra as mulheres\u201d da historiadora Dra. Ana Maria Colling,\njuntamente com a artista Gra\u00e7a Craidy, que falou sobre suas obras, e contou com\nas seguintes exposi\u00e7\u00f5es:<\/p>\n\n\n\n<p>&#8211; \u201cAt\u00e9 que a morte nos separe\u201d da artista visual Gra\u00e7a Craidy;<\/p>\n\n\n\n<p>&#8211; \u201cVer-me vista\u201d da fot\u00f3grafa Marielen Baldissera;<\/p>\n\n\n\n<p>&#8211; \u201cMulheres invis\u00edveis\u201d da fot\u00f3grafa Desir\u00e9e Ferreira;<\/p>\n\n\n\n<p>&#8211; \u201cMulheres: Resist\u00eancia e Cultura, de Porto Hist\u00f3ria PH&#8221;.<\/p>\n\n\n\n<p>No dia 27 de abril tamb\u00e9m aconteceu a palestra \u201cDemocracia, representatividade pol\u00edtica e g\u00eanero feminino no Brasil: progressos e desafios do Direito Eleitoral, com a servidora do TRE&#8221; e mestre em Direito pela Universidade de Coimbra, Adriana Sampaio.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Institui\u00e7\u00f5es parceiras:<\/h4>\n\n\n\n<ul class=\"wp-block-list\"><li>DPU<\/li><li>TRE<\/li><li>Se\u00e7\u00e3o Judici\u00e1ria de SC<\/li><li>TJRS<\/li><li>Se\u00e7\u00e3o Judici\u00e1ria do Paran\u00e1<\/li><li>TRF4<\/li><li>TRT4<\/li><li>Memorial da C\u00e2mara Municipal de Porto Alegre<\/li><li>Projeto Pescar<\/li><li>Porto PH Hist\u00f3ria<\/li><\/ul>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante os anos 2016 e 2017 foi realizado o evento \u201cDireitos Humanos, uma quest\u00e3o de justi\u00e7a\u201d, com objetivo de proporcionar espa\u00e7o para reflex\u00e3o sobre o tema e suas conex\u00f5es com o cotidiano da sociedade, por meio de exposi\u00e7\u00f5es, palestras e [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-33863","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/homologa.jfrs.jus.br\/memoria\/wp-json\/wp\/v2\/posts\/33863","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/homologa.jfrs.jus.br\/memoria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/homologa.jfrs.jus.br\/memoria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/homologa.jfrs.jus.br\/memoria\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/homologa.jfrs.jus.br\/memoria\/wp-json\/wp\/v2\/comments?post=33863"}],"version-history":[{"count":1,"href":"https:\/\/homologa.jfrs.jus.br\/memoria\/wp-json\/wp\/v2\/posts\/33863\/revisions"}],"predecessor-version":[{"id":35786,"href":"https:\/\/homologa.jfrs.jus.br\/memoria\/wp-json\/wp\/v2\/posts\/33863\/revisions\/35786"}],"wp:attachment":[{"href":"https:\/\/homologa.jfrs.jus.br\/memoria\/wp-json\/wp\/v2\/media?parent=33863"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/homologa.jfrs.jus.br\/memoria\/wp-json\/wp\/v2\/categories?post=33863"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/homologa.jfrs.jus.br\/memoria\/wp-json\/wp\/v2\/tags?post=33863"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}