{"id":19214,"date":"2015-02-18T13:55:51","date_gmt":"2015-02-18T16:55:51","guid":{"rendered":"https:\/\/homologa.jfrs.jus.br\/memoria\/?page_id=19214"},"modified":"2022-09-26T16:04:23","modified_gmt":"2022-09-26T19:04:23","slug":"32a-feira-do-livro-novo-hamburgo","status":"publish","type":"post","link":"https:\/\/homologa.jfrs.jus.br\/memoria\/32a-feira-do-livro-novo-hamburgo\/","title":{"rendered":"32\u00aa Feira do Livro &#8211; Novo Hamburgo"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<h2 class=\"has-text-align-center has-text-color wp-block-heading\" style=\"color:#035579\"><strong>Participa\u00e7\u00e3o na Feira Regional do Livro de Novo Hamburgo \u2013 outubro\/2014<\/strong><\/h2>\n\n\n\n<p><\/p>\n\n\n\n<p>A Justi\u00e7a Federal ga\u00facha participou, pela primeira vez, da Feira Regional do Livro de Novo Hamburgo, realizada entre os dias 10 e 18 de outubro de 2014.<\/p>\n\n\n\n<p>O N\u00facleo de Documenta\u00e7\u00e3o e Mem\u00f3ria apresentou um recorte da exposi\u00e7\u00e3o O Sonho Brasileiro da Casa Pr\u00f3pria, junto ao estande da Justi\u00e7a Federal do RS, na qual foi realizado um trabalho em parceria com a equipe do CEJUSCON dessa cidade.<\/p>\n\n\n\n<p>O evento O Sonho Brasileiro da Casa Pr\u00f3pria, aconteceu na Subse\u00e7\u00e3o Judici\u00e1ria de Porto Alegre, no m\u00eas de maio\/2014, dando visibilidade \u00e0s compet\u00eancias da institui\u00e7\u00e3o para a resolu\u00e7\u00e3o de conflitos que permeiam a tem\u00e1tica da habita\u00e7\u00e3o.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/homologa.jfrs.jus.br\/memoria\/wp-content\/uploads\/2022\/09\/Feira-do-Livro-em-Novo-Hamburgo.EDITADO.png\" alt=\"Uma sala com um gabinete dentro (com divis\u00f3rias com vidros ). Dentro do gabinete se observa mesa, cadeiras e um banner da justi\u00e7a federal. No espa\u00e7o da sala, ao fundo da parede, h\u00e1 um sof\u00e1 marrom com objetos em cima. Em cada lado do sof\u00e1 h\u00e1 montagens com cubos estilizados, imitando tijolos , janelas, formando uma maquete de pequenas casas. Mais \u00e0 frente, na frente do gabinete , a mesma maquete com cubos. Observa-se a figura de uma fam\u00edlia dentro de um dos cubos que \u00e9 vazado.\" class=\"wp-image-63069\" width=\"405\" height=\"297\"\/><figcaption>Estande da JFRS na 32\u00aa Feira do Livro em Novo Hamburgo &#8211; RS.<\/figcaption><\/figure><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Participa\u00e7\u00e3o na Feira Regional do Livro de Novo Hamburgo \u2013 outubro\/2014 A Justi\u00e7a Federal ga\u00facha participou, pela primeira vez, da Feira Regional do Livro de Novo Hamburgo, realizada entre os dias 10 e 18 de outubro de 2014. O N\u00facleo [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25,21],"tags":[],"class_list":["post-19214","post","type-post","status-publish","format-standard","hentry","category-25","category-exposicoes-e-eventos"],"_links":{"self":[{"href":"https:\/\/homologa.jfrs.jus.br\/memoria\/wp-json\/wp\/v2\/posts\/19214","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/homologa.jfrs.jus.br\/memoria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/homologa.jfrs.jus.br\/memoria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/homologa.jfrs.jus.br\/memoria\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/homologa.jfrs.jus.br\/memoria\/wp-json\/wp\/v2\/comments?post=19214"}],"version-history":[{"count":2,"href":"https:\/\/homologa.jfrs.jus.br\/memoria\/wp-json\/wp\/v2\/posts\/19214\/revisions"}],"predecessor-version":[{"id":35684,"href":"https:\/\/homologa.jfrs.jus.br\/memoria\/wp-json\/wp\/v2\/posts\/19214\/revisions\/35684"}],"wp:attachment":[{"href":"https:\/\/homologa.jfrs.jus.br\/memoria\/wp-json\/wp\/v2\/media?parent=19214"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/homologa.jfrs.jus.br\/memoria\/wp-json\/wp\/v2\/categories?post=19214"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/homologa.jfrs.jus.br\/memoria\/wp-json\/wp\/v2\/tags?post=19214"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}